{"id":12128,"date":"2021-03-19T11:27:25","date_gmt":"2021-03-19T10:27:25","guid":{"rendered":"https:\/\/www.ness.de\/recuperation-de-chaleur\/"},"modified":"2021-03-23T10:15:14","modified_gmt":"2021-03-23T09:15:14","slug":"recuperation-de-chaleur","status":"publish","type":"page","link":"https:\/\/ness.de\/fr\/recuperation-de-chaleur\/","title":{"rendered":"R\u00e9cup\u00e9ration de chaleur"},"content":{"rendered":"<section  class='av_textblock_section av-jikbywl1-59eb46e57a41fca6bbe75c10c01e1820 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h1 style=\"text-align: center;\">R\u00e9cup\u00e9ration de chaleur<\/h1>\n<h2 style=\"text-align: center;\">Exploitation plus efficace des ressources existantes<\/h2>\n<\/div><\/section>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-jikjuuzc-358eb38c012e01cf052584db60adfad7\">\n#top .hr.hr-invisible.av-jikjuuzc-358eb38c012e01cf052584db60adfad7{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-jikjuuzc-358eb38c012e01cf052584db60adfad7 hr-invisible  avia-builder-el-1  el_after_av_textblock  el_before_av_image '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-jikctntd-d9254424affcabe566a1212608ddd5e7\">\n.avia-image-container.av-jikctntd-d9254424affcabe566a1212608ddd5e7 img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-jikctntd-d9254424affcabe566a1212608ddd5e7 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-jikctntd-d9254424affcabe566a1212608ddd5e7 av-styling- avia-align-center  avia-builder-el-2  el_after_av_hr  el_before_av_section  avia-builder-el-last '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-12131 avia-img-lazy-loading-not-12131 avia_image ' src=\"https:\/\/ness.de\/wp-content\/uploads\/2018\/07\/slider-efficiency-1210x423.jpg\" alt='' title='slider-efficiency'  height=\"423\" width=\"1210\"  itemprop=\"thumbnailUrl\"  \/><\/div><\/div><\/div>\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='av_section_1'  class='avia-section av-63tsp-f56bc69621f462b60ff782c47dd8762c main_color avia-section-default avia-no-border-styling  avia-builder-el-3  el_after_av_image  el_before_av_section  avia-bg-style-scroll container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-12128'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1jyeqh-4ef1e849578942577eecfb0c99ac3f6d\">\n.flex_column.av-1jyeqh-4ef1e849578942577eecfb0c99ac3f6d{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-1jyeqh-4ef1e849578942577eecfb0c99ac3f6d av_one_half  avia-builder-el-4  el_before_av_one_half  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><section  class='av_textblock_section av-jikc530y-fbf7e560c6b6e522145385effc680a03 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2>Exploitation plus efficace des ressources existantes<\/h2>\n<p>Une utilisation int\u00e9ressante pour votre r\u00e9chauffeur d&rsquo;huile caloporteuse est la r\u00e9cup\u00e9ration de chaleur \u00e0 travers un pr\u00e9chauffeur d&rsquo;air de combustion (Luvo). Le Luvo permet d&rsquo;exploiter activement l&rsquo;\u00e9nergie des gaz r\u00e9siduaires \u00e0 la sortie du r\u00e9chauffeur pour r\u00e9duire les d\u00e9penses d&rsquo;\u00e9nergie et \u00e9conomiser les mati\u00e8res premi\u00e8res ! Avec ce type de r\u00e9cup\u00e9ration de la chaleur, vous pouvez non seulement \u00e9conomiser du combustible, mais aussi r\u00e9duire activement les \u00e9missions CO\u2082 de votre installation.<\/p>\n<p>Experts du chauffage de processus, nous sommes le partenaire id\u00e9al pour tout ce qui concerne le r\u00e9glage de la temp\u00e9rature de vos installations de production. Tous les produits NESS sont optimis\u00e9s du point de vue thermodynamique. Nous accordons beaucoup d&rsquo;importance au rendement, \u00e0 la durabilit\u00e9, \u00e0 la s\u00e9curit\u00e9 et \u00e0 la disponibilit\u00e9 ainsi qu&rsquo;\u00e0 l&rsquo;efficacit\u00e9 du transfert de chaleur de nos installations. Notre \u00e9quipe Ing\u00e9nierie se penche volontiers avec vous sur de nouveaux concepts de solution.<\/p>\n<p>Parce que nous avons \u00e0 c\u0153ur votre succ\u00e8s, nous optimisons vos installations pour vos exigences individuelles.<\/p>\n<\/div><\/section><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-51gmh-4d29f50bc90b046fadb23c23e6e0397c\">\n.flex_column.av-51gmh-4d29f50bc90b046fadb23c23e6e0397c{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-51gmh-4d29f50bc90b046fadb23c23e6e0397c av_one_half  avia-builder-el-6  el_after_av_one_half  avia-builder-el-last  flex_column_div av-zero-column-padding  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-jikcduf3-29830bf4348b785f4873b87506a36ea5\">\n#top .avia-icon-list-container.av-jikcduf3-29830bf4348b785f4873b87506a36ea5 .iconlist_icon{\ncolor:#e1081a;\nbackground-color:#ffffff;\nborder:1px solid #e1081a;\n}\n#top .avia-icon-list-container.av-jikcduf3-29830bf4348b785f4873b87506a36ea5 .iconlist_icon svg:first-child{\nstroke:#e1081a;\nfill:#e1081a;\n}\n<\/style>\n<div  class='avia-icon-list-container av-jikcduf3-29830bf4348b785f4873b87506a36ea5  avia-builder-el-7  avia-builder-el-no-sibling '><ul class='avia-icon-list avia_animate_when_almost_visible avia-icon-list-left av-iconlist-big av-jikcduf3-29830bf4348b785f4873b87506a36ea5 avia-iconlist-animate'>\n<li><div class='iconlist_icon av-a8v7i-759970fc77446ce17e3b18f3f8a37cfb avia-font-entypo-fontello avia-iconfont avia-font-entypo-fontello'><span class='av-icon-char' data-av_icon='\ue8c5' data-av_iconfont='entypo-fontello' aria-hidden=\"true\"><\/span><\/div><article class=\"article-icon-entry \"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\" aria-label=\"Ic\u00f4ne : Am\u00e9lioration de l\u2019efficacit\u00e9\"><h4 class='av_iconlist_title iconlist_title  '  itemprop=\"headline\" >Am\u00e9lioration de l\u2019efficacit\u00e9<\/h4><\/header><div class='iconlist_content '  itemprop=\"text\" ><p>Exploitation de l&rsquo;\u00e9nergie thermique par la r\u00e9cup\u00e9ration de chaleur<\/p>\n<\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<li><div class='iconlist_icon av-el3fq-92e9d2a6430630f6194566753439a216 avia-font-entypo-fontello avia-iconfont avia-font-entypo-fontello'><span class='av-icon-char' data-av_icon='\ue8de' data-av_iconfont='entypo-fontello' aria-hidden=\"true\"><\/span><\/div><article class=\"article-icon-entry \"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\" aria-label=\"Ic\u00f4ne : Puissance\"><h4 class='av_iconlist_title iconlist_title  '  itemprop=\"headline\" >Puissance<\/h4><\/header><div class='iconlist_content '  itemprop=\"text\" ><p>Pour r\u00e9chauffeurs de 630 kW \u00e0 16.000 kW<\/p>\n<\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<li><div class='iconlist_icon av-8ji3q-1c9b3cbc2ac8c65ff01680e9cd745f58 avia-font-entypo-fontello avia-iconfont avia-font-entypo-fontello'><span class='av-icon-char' data-av_icon='\ue8b8' data-av_iconfont='entypo-fontello' aria-hidden=\"true\"><\/span><\/div><article class=\"article-icon-entry \"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\" aria-label=\"Ic\u00f4ne : Durabilit\u00e9\"><h4 class='av_iconlist_title iconlist_title  '  itemprop=\"headline\" >Durabilit\u00e9<\/h4><\/header><div class='iconlist_content '  itemprop=\"text\" ><p>Exploitation durable des ressources pr\u00e9cieuses et r\u00e9duction des \u00e9missions de CO\u2082<\/p>\n<\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<li><div class='iconlist_icon av-aqmva-08992213ec1d41d0492978a84a29c245 avia-font-entypo-fontello avia-iconfont avia-font-entypo-fontello'><span class='av-icon-char' data-av_icon='\ue8e3' data-av_iconfont='entypo-fontello' aria-hidden=\"true\"><\/span><\/div><article class=\"article-icon-entry \"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\" aria-label=\"Ic\u00f4ne : R\u00e9duction des co\u00fbts\"><h4 class='av_iconlist_title iconlist_title  '  itemprop=\"headline\" >R\u00e9duction des co\u00fbts<\/h4><\/header><div class='iconlist_content '  itemprop=\"text\" ><p>Installation en seconde monte pour une r\u00e9duction durable des co\u00fbts d&rsquo;exploitation et un retour sur investissement rapide<\/p>\n<\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<\/ul><\/div><\/div>\n\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-jio9mmpx-d33e6e161c62c9597b403568151100a2\">\n.avia-section.av-jio9mmpx-d33e6e161c62c9597b403568151100a2 .av-parallax .av-parallax-inner{\nbackground-color:#969696;\nbackground-image:url(https:\/\/ness.de\/wp-content\/uploads\/2018\/06\/Fa.jpg);\nbackground-repeat:no-repeat;\nbackground-position:50% 0%;\nbackground-attachment:scroll;\n}\n.avia-section.av-jio9mmpx-d33e6e161c62c9597b403568151100a2 .av-section-color-overlay{\nopacity:0.3;\nbackground-color:#0a0a0a;\n}\n<\/style>\n<div id='av_section_2'  class='avia-section av-jio9mmpx-d33e6e161c62c9597b403568151100a2 main_color avia-section-default avia-no-border-styling  avia-builder-el-8  el_after_av_section  el_before_av_section  avia-full-stretch av-parallax-section avia-bg-style-parallax av-section-color-overlay-active av-minimum-height av-minimum-height-25 av-height-25  container_wrap sidebar_right'  data-section-bg-repeat='stretch' data-av_minimum_height_pc='25' data-av_min_height_opt='25'><div class='av-parallax' data-avia-parallax-ratio='0.3' ><div class='av-parallax-inner main_color avia-full-stretch'><\/div><\/div><div class=\"av-section-color-overlay-wrap\"><div class=\"av-section-color-overlay\"><\/div><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-12128'><div class='entry-content-wrapper clearfix'>\n<section  class='av_textblock_section av-jikbywl1-59eb46e57a41fca6bbe75c10c01e1820 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h3 style=\"text-align: center;\"><span style=\"color: #ffffff;\">Sch\u00e9ma du pr\u00e9chauffage de l&rsquo;air<br \/>\n<\/span><\/h3>\n<h2 style=\"text-align: center;\"><span style=\"color: #ffffff;\"><em><strong><span style=\"color: #e1081a;\">#1\u00a0<\/span><\/strong><span style=\"color: #ffffff;\"> Am\u00e9lioration de l&rsquo;efficacit\u00e9 par l&rsquo;exploitation de l&rsquo;\u00e9nergie du gaz de combustion<br \/>\n<\/span><\/em><\/span><\/h2>\n<h2 style=\"text-align: center;\"><em><span style=\"color: #ffffff;\"><strong><span style=\"color: #e1081a;\">#2<\/span><\/strong><span style=\"color: #e1081a;\">\u00a0<\/span> \u00c9conomie de combustible par l&rsquo;utilisation d&rsquo;air pr\u00e9chauff\u00e9<br \/>\n<\/span><\/em><\/h2>\n<\/div><\/section>\n\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-jio9mmpx-a13ef04830bca3aa06de1c4e224a197a\">\n.avia-section.av-jio9mmpx-a13ef04830bca3aa06de1c4e224a197a{\nbackground-color:#f2f2f2;\nbackground-image:unset;\n}\n<\/style>\n<div id='av_section_3'  class='avia-section av-jio9mmpx-a13ef04830bca3aa06de1c4e224a197a main_color avia-section-default avia-no-border-styling  avia-builder-el-10  el_after_av_section  el_before_av_section  avia-bg-style-scroll container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-12128'><div class='entry-content-wrapper clearfix'>\n<section  class='av_textblock_section av-jikbywl1-59eb46e57a41fca6bbe75c10c01e1820 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2 style=\"text-align: center;\">R\u00e9duction durable des co\u00fbts avec peu d&rsquo;effort<\/h2>\n<\/div><\/section>\n\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='av_section_4'  class='avia-section av-63tsp-f56bc69621f462b60ff782c47dd8762c main_color avia-section-default avia-no-border-styling  avia-builder-el-12  el_after_av_section  el_before_av_section  avia-bg-style-scroll container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-12128'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-ehp5q-86f491b3f7800075fd81a62da2204e61\">\n.flex_column.av-ehp5q-86f491b3f7800075fd81a62da2204e61{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-ehp5q-86f491b3f7800075fd81a62da2204e61 av_one_half  avia-builder-el-13  el_before_av_one_half  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><section  class='av_textblock_section av-jikc530y-413ee3f717d786fef62d59c0c9a93bc7 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2><b>NESS <\/b><em><strong>Pr\u00e9chauffeur d&rsquo;air de combustion (Luvo)<\/strong><br \/>\n<\/em><\/h2>\n<h3><strong><em>Am\u00e9lioration de l&rsquo;efficacit\u00e9 et \u00e9conomie de ressources<\/em><\/strong><\/h3>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k1nj0x70-5628085bb49f9c51af5f211bb3e6b154\">\n#top .hr.hr-invisible.av-k1nj0x70-5628085bb49f9c51af5f211bb3e6b154{\nheight:20px;\n}\n<\/style>\n<div  class='hr av-k1nj0x70-5628085bb49f9c51af5f211bb3e6b154 hr-invisible  avia-builder-el-15  el_after_av_textblock  el_before_av_image '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-jok4lrt1-321d96daea3bc6b657122d4e61abf5d3\">\n.avia-image-container.av-jok4lrt1-321d96daea3bc6b657122d4e61abf5d3 img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-jok4lrt1-321d96daea3bc6b657122d4e61abf5d3 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-jok4lrt1-321d96daea3bc6b657122d4e61abf5d3 av-styling- avia-align-center  avia-builder-el-16  el_after_av_hr  el_before_av_hr '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-13079 avia-img-lazy-loading-not-13079 avia_image ' src=\"https:\/\/ness.de\/wp-content\/uploads\/2021\/03\/Funktionsweise_Luvo_web_FR-1030x421.png\" alt='' title='Funktionsweise_Luvo_web_FR'  height=\"421\" width=\"1030\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/ness.de\/wp-content\/uploads\/2021\/03\/Funktionsweise_Luvo_web_FR-1030x421.png 1030w, https:\/\/ness.de\/wp-content\/uploads\/2021\/03\/Funktionsweise_Luvo_web_FR-300x123.png 300w, https:\/\/ness.de\/wp-content\/uploads\/2021\/03\/Funktionsweise_Luvo_web_FR-768x314.png 768w, https:\/\/ness.de\/wp-content\/uploads\/2021\/03\/Funktionsweise_Luvo_web_FR-1536x628.png 1536w, https:\/\/ness.de\/wp-content\/uploads\/2021\/03\/Funktionsweise_Luvo_web_FR-2048x837.png 2048w, https:\/\/ness.de\/wp-content\/uploads\/2021\/03\/Funktionsweise_Luvo_web_FR-1500x613.png 1500w, https:\/\/ness.de\/wp-content\/uploads\/2021\/03\/Funktionsweise_Luvo_web_FR-705x288.png 705w, https:\/\/ness.de\/wp-content\/uploads\/2021\/03\/Funktionsweise_Luvo_web_FR-450x184.png 450w, https:\/\/ness.de\/wp-content\/uploads\/2021\/03\/Funktionsweise_Luvo_web_FR-1320x540.png 1320w\" sizes=\"(max-width: 1030px) 100vw, 1030px\" \/><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k1nj0x70-601c68a2c9e1a0caaa0057778be0bca1\">\n#top .hr.hr-invisible.av-k1nj0x70-601c68a2c9e1a0caaa0057778be0bca1{\nheight:10px;\n}\n<\/style>\n<div  class='hr av-k1nj0x70-601c68a2c9e1a0caaa0057778be0bca1 hr-invisible  avia-builder-el-17  el_after_av_image  el_before_av_textblock '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='av_textblock_section av-jikc530y-413ee3f717d786fef62d59c0c9a93bc7 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>Une utilisation durable pour votre installation est la r\u00e9cup\u00e9ration de chaleur \u00e0 travers un pr\u00e9chauffeur d&rsquo;air de combustion (Luvo). Le Luvo permet d&rsquo;exploiter activement l&rsquo;\u00e9nergie des gaz de combustion chauds \u00e0 la sortie du r\u00e9chauffeur pour r\u00e9duire les d\u00e9penses d&rsquo;\u00e9nergie et \u00e9conomiser le combustible ! Et en plus, vous r\u00e9duisez les \u00e9missions de CO2 de votre installation.<\/p>\n<p>Pour chauffer l&rsquo;agent caloporteur \u00e0 la temp\u00e9rature requise, la temp\u00e9rature du gaz de combustion doit \u00eatre sup\u00e9rieure \u00e0 celle de l&rsquo;agent Les r\u00e9chauffeurs standards \u00e9vacuent ce gaz r\u00e9siduaire sans en exploiter l&rsquo;\u00e9nergie thermique. Les pr\u00e9chauffeurs d&rsquo;air de combustion exploitent une part importante de l&rsquo;\u00e9nergie contenue dans le gaz de combustion pour pr\u00e9chauffer l&rsquo;air de combustion. Ainsi, ils permettent d&rsquo;\u00e9conomiser du combustible.<\/p>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-joinzcn0-98aebc4d9311523842c959437dfcde4b\">\n#top .hr.hr-invisible.av-joinzcn0-98aebc4d9311523842c959437dfcde4b{\nheight:25px;\n}\n<\/style>\n<div  class='hr av-joinzcn0-98aebc4d9311523842c959437dfcde4b hr-invisible  avia-builder-el-19  el_after_av_textblock  el_before_av_buttonrow '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<div  class='avia-buttonrow-wrap av-jikciwkr-2e4bdf3f895634d29ca6ab2ad1bb9330 avia-buttonrow-left  avia-builder-el-20  el_after_av_hr  avia-builder-el-last '>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_buttonrow_item-1e6090583139f6d600468b4b578d3fac\">\n#top #wrap_all .avia-button.av-av_buttonrow_item-1e6090583139f6d600468b4b578d3fac{\nbackground-color:#e1081a;\nborder-color:#e1081a;\ncolor:#ffffff;\ntransition:all 0.4s ease-in-out;\nmargin-bottom:5px;\nmargin-right:5px;\n}\n#top #wrap_all .avia-button.av-av_buttonrow_item-1e6090583139f6d600468b4b578d3fac .avia-svg-icon svg:first-child{\nfill:#ffffff;\nstroke:#ffffff;\n}\n<\/style>\n<a href='https:\/\/ness.de\/wp-content\/uploads\/2021\/03\/NESS-Luvo_V01_02_FR.pdf'  class='avia-button av-av_buttonrow_item-1e6090583139f6d600468b4b578d3fac avia-icon_select-no avia-size-large'  target=\"_blank\"  rel=\"noopener noreferrer\"  aria-label=\"Fiches de donn\u00e9es - NESS Pr\u00e9chauffeur d\u2019air de combustion (Luvo)\"><span class='avia_iconbox_title' >Fiches de donn\u00e9es - NESS Pr\u00e9chauffeur d\u2019air de combustion (Luvo)<\/span><\/a>\n<\/div><\/p><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-ehp5q-c8e81032bcfa40cd8cf5c028e47b330a\">\n.flex_column.av-ehp5q-c8e81032bcfa40cd8cf5c028e47b330a{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-ehp5q-c8e81032bcfa40cd8cf5c028e47b330a av_one_half  avia-builder-el-21  el_after_av_one_half  avia-builder-el-last  flex_column_div av-zero-column-padding  '     ><section  class='av_textblock_section av-jikc530y-fbf7e560c6b6e522145385effc680a03 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h3><strong><em>Retour sur investissement rapide<br \/>\n<\/em><\/strong><\/h3>\n<p>Le retour sur investissement est relativement rapide, selon le taux d&rsquo;utilisation du r\u00e9chauffeur et le prix du courant.<\/p>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-joinzcn0-98aebc4d9311523842c959437dfcde4b\">\n#top .hr.hr-invisible.av-joinzcn0-98aebc4d9311523842c959437dfcde4b{\nheight:25px;\n}\n<\/style>\n<div  class='hr av-joinzcn0-98aebc4d9311523842c959437dfcde4b hr-invisible  avia-builder-el-23  el_after_av_textblock  el_before_av_image '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-jok4lrt1-2c2144da150385315b9ef3500a68dc7b\">\n.avia-image-container.av-jok4lrt1-2c2144da150385315b9ef3500a68dc7b img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-jok4lrt1-2c2144da150385315b9ef3500a68dc7b .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-jok4lrt1-2c2144da150385315b9ef3500a68dc7b av-styling- avia-align-center  avia-builder-el-24  el_after_av_hr  avia-builder-el-last '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-13083 avia-img-lazy-loading-not-13083 avia_image ' src=\"https:\/\/ness.de\/wp-content\/uploads\/2021\/03\/LuVo_savings_FR-1030x679.png\" alt='' title='LuVo_savings_FR'  height=\"679\" width=\"1030\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/ness.de\/wp-content\/uploads\/2021\/03\/LuVo_savings_FR-1030x679.png 1030w, https:\/\/ness.de\/wp-content\/uploads\/2021\/03\/LuVo_savings_FR-300x198.png 300w, https:\/\/ness.de\/wp-content\/uploads\/2021\/03\/LuVo_savings_FR-768x506.png 768w, https:\/\/ness.de\/wp-content\/uploads\/2021\/03\/LuVo_savings_FR-1536x1013.png 1536w, https:\/\/ness.de\/wp-content\/uploads\/2021\/03\/LuVo_savings_FR-1500x989.png 1500w, https:\/\/ness.de\/wp-content\/uploads\/2021\/03\/LuVo_savings_FR-705x465.png 705w, https:\/\/ness.de\/wp-content\/uploads\/2021\/03\/LuVo_savings_FR-450x297.png 450w, https:\/\/ness.de\/wp-content\/uploads\/2021\/03\/LuVo_savings_FR-1320x871.png 1320w, https:\/\/ness.de\/wp-content\/uploads\/2021\/03\/LuVo_savings_FR.png 1815w\" sizes=\"(max-width: 1030px) 100vw, 1030px\" \/><\/div><\/div><\/div><\/p><\/div><\/div><\/div><\/div><!-- close content main div --><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-63tsp-6ee37fe6939a01790ffa9b9a5e95a35b\">\n.avia-section.av-63tsp-6ee37fe6939a01790ffa9b9a5e95a35b{\nbackground-color:#f7f7f7;\nbackground-image:unset;\n}\n<\/style>\n<div id='av_section_5'  class='avia-section av-63tsp-6ee37fe6939a01790ffa9b9a5e95a35b main_color avia-section-default avia-no-border-styling  avia-builder-el-25  el_after_av_section  avia-builder-el-last  avia-bg-style-scroll container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-12128'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-ehp5q-86f491b3f7800075fd81a62da2204e61\">\n.flex_column.av-ehp5q-86f491b3f7800075fd81a62da2204e61{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-ehp5q-86f491b3f7800075fd81a62da2204e61 av_three_fourth  avia-builder-el-26  avia-builder-el-no-sibling  first flex_column_div av-zero-column-padding  '     ><section  class='av_textblock_section av-jikc530y-fbf7e560c6b6e522145385effc680a03 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p style=\"text-align: left;\"><em>Exemples d&rsquo;\u00e9conomie des co\u00fbts \u2013 Luvo:<\/em><\/p>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-joinzcn0-98aebc4d9311523842c959437dfcde4b\">\n#top .hr.hr-invisible.av-joinzcn0-98aebc4d9311523842c959437dfcde4b{\nheight:25px;\n}\n<\/style>\n<div  class='hr av-joinzcn0-98aebc4d9311523842c959437dfcde4b hr-invisible  avia-builder-el-28  el_after_av_textblock  el_before_av_image_hotspot  avia-builder-el-last '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<div  class='av-hotspot-image-container av-jiptewrl-a83c2ef3cd180b74837f88c2be1b3319  avia-builder-el-29  el_after_av_hr  avia-builder-el-last  av-hotspot-numbered av-mobile-fallback-active  av-non-fullwidth-hotspot-image'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class='av-hotspot-container'><div class='av-hotspot-container-inner-cell'><div class='av-hotspot-container-inner-wrap'><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-13087 avia-img-lazy-loading-not-13087 avia_image' src=\"https:\/\/ness.de\/wp-content\/uploads\/2021\/03\/Tabelle_Ersparnis_FR-1030x669.png\" alt='' title='Tabelle_Ersparnis_FR'  height=\"669\" width=\"1030\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/ness.de\/wp-content\/uploads\/2021\/03\/Tabelle_Ersparnis_FR-1030x669.png 1030w, https:\/\/ness.de\/wp-content\/uploads\/2021\/03\/Tabelle_Ersparnis_FR-300x195.png 300w, https:\/\/ness.de\/wp-content\/uploads\/2021\/03\/Tabelle_Ersparnis_FR-768x499.png 768w, https:\/\/ness.de\/wp-content\/uploads\/2021\/03\/Tabelle_Ersparnis_FR-1536x997.png 1536w, https:\/\/ness.de\/wp-content\/uploads\/2021\/03\/Tabelle_Ersparnis_FR-2048x1330.png 2048w, https:\/\/ness.de\/wp-content\/uploads\/2021\/03\/Tabelle_Ersparnis_FR-1500x974.png 1500w, https:\/\/ness.de\/wp-content\/uploads\/2021\/03\/Tabelle_Ersparnis_FR-705x458.png 705w, https:\/\/ness.de\/wp-content\/uploads\/2021\/03\/Tabelle_Ersparnis_FR-450x292.png 450w, https:\/\/ness.de\/wp-content\/uploads\/2021\/03\/Tabelle_Ersparnis_FR-1320x857.png 1320w\" sizes=\"(max-width: 1030px) 100vw, 1030px\" \/><\/div><\/div><\/div><\/div><\/p><\/div><\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='after_section_5'  class='main_color av_default_container_wrap container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-12128'><div class='entry-content-wrapper clearfix'><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-12128","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>R\u00e9cup\u00e9ration de chaleur pour augmenter l&#039;efficacit\u00e9 - NESS W\u00e4rmetechnik<\/title>\n<meta name=\"description\" content=\"Le pr\u00e9chauffeur d&#039;air de combustion permet d&#039;exploiter activement l&#039;\u00e9nergie des gaz r\u00e9siduaires \u00e0 la sortie du r\u00e9chauffeur pour r\u00e9duire les d\u00e9penses d&#039;\u00e9nergie et \u00e9conomiser les mati\u00e8res premi\u00e8res !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ness.de\/fr\/recuperation-de-chaleur\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00e9cup\u00e9ration de chaleur\" \/>\n<meta property=\"og:description\" content=\"Le pr\u00e9chauffeur d&#039;air de combustion permet d&#039;exploiter activement l&#039;\u00e9nergie des gaz r\u00e9siduaires \u00e0 la sortie du r\u00e9chauffeur pour r\u00e9duire les d\u00e9penses d&#039;\u00e9nergie et \u00e9conomiser les mati\u00e8res premi\u00e8res !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ness.de\/fr\/recuperation-de-chaleur\/\" \/>\n<meta property=\"og:site_name\" content=\"NESS W\u00e4rmetechnik\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-23T09:15:14+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"R\u00e9cup\u00e9ration de chaleur pour augmenter l'efficacit\u00e9 - NESS W\u00e4rmetechnik","description":"Le pr\u00e9chauffeur d'air de combustion permet d'exploiter activement l'\u00e9nergie des gaz r\u00e9siduaires \u00e0 la sortie du r\u00e9chauffeur pour r\u00e9duire les d\u00e9penses d'\u00e9nergie et \u00e9conomiser les mati\u00e8res premi\u00e8res !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ness.de\/fr\/recuperation-de-chaleur\/","og_locale":"fr_FR","og_type":"article","og_title":"R\u00e9cup\u00e9ration de chaleur","og_description":"Le pr\u00e9chauffeur d'air de combustion permet d'exploiter activement l'\u00e9nergie des gaz r\u00e9siduaires \u00e0 la sortie du r\u00e9chauffeur pour r\u00e9duire les d\u00e9penses d'\u00e9nergie et \u00e9conomiser les mati\u00e8res premi\u00e8res !","og_url":"https:\/\/ness.de\/fr\/recuperation-de-chaleur\/","og_site_name":"NESS W\u00e4rmetechnik","article_modified_time":"2021-03-23T09:15:14+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ness.de\/fr\/recuperation-de-chaleur\/","url":"https:\/\/ness.de\/fr\/recuperation-de-chaleur\/","name":"R\u00e9cup\u00e9ration de chaleur pour augmenter l'efficacit\u00e9 - NESS W\u00e4rmetechnik","isPartOf":{"@id":"https:\/\/ness.de\/#website"},"datePublished":"2021-03-19T10:27:25+00:00","dateModified":"2021-03-23T09:15:14+00:00","description":"Le pr\u00e9chauffeur d'air de combustion permet d'exploiter activement l'\u00e9nergie des gaz r\u00e9siduaires \u00e0 la sortie du r\u00e9chauffeur pour r\u00e9duire les d\u00e9penses d'\u00e9nergie et \u00e9conomiser les mati\u00e8res premi\u00e8res !","breadcrumb":{"@id":"https:\/\/ness.de\/fr\/recuperation-de-chaleur\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ness.de\/fr\/recuperation-de-chaleur\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ness.de\/fr\/recuperation-de-chaleur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/ness.de\/fr\/"},{"@type":"ListItem","position":2,"name":"R\u00e9cup\u00e9ration de chaleur"}]},{"@type":"WebSite","@id":"https:\/\/ness.de\/#website","url":"https:\/\/ness.de\/","name":"NESS W\u00e4rmetechnik","description":"The Process Heat Company","publisher":{"@id":"https:\/\/ness.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ness.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/ness.de\/#organization","name":"NESS W\u00e4rmetechnik GmbH","url":"https:\/\/ness.de\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ness.de\/#\/schema\/logo\/image\/","url":"https:\/\/ness.de\/wp-content\/uploads\/2018\/06\/ness_logo_web-01.png","contentUrl":"https:\/\/ness.de\/wp-content\/uploads\/2018\/06\/ness_logo_web-01.png","width":492,"height":210,"caption":"NESS W\u00e4rmetechnik GmbH"},"image":{"@id":"https:\/\/ness.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/12209647\/","https:\/\/www.youtube.com\/channel\/UCDhnohU-u-vr6G2SDUw0dbQ"]}]}},"_links":{"self":[{"href":"https:\/\/ness.de\/fr\/wp-json\/wp\/v2\/pages\/12128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ness.de\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ness.de\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ness.de\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ness.de\/fr\/wp-json\/wp\/v2\/comments?post=12128"}],"version-history":[{"count":6,"href":"https:\/\/ness.de\/fr\/wp-json\/wp\/v2\/pages\/12128\/revisions"}],"predecessor-version":[{"id":13098,"href":"https:\/\/ness.de\/fr\/wp-json\/wp\/v2\/pages\/12128\/revisions\/13098"}],"wp:attachment":[{"href":"https:\/\/ness.de\/fr\/wp-json\/wp\/v2\/media?parent=12128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}